{"id":93892,"date":"2021-06-09T11:00:55","date_gmt":"2021-06-09T14:00:55","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=93892"},"modified":"2021-06-09T11:01:00","modified_gmt":"2021-06-09T14:01:00","slug":"colision-entre-un-automovil-y-una-motocicleta-2","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/colision-entre-un-automovil-y-una-motocicleta-2\/","title":{"rendered":"Colisi\u00f3n entre un autom\u00f3vil y una motocicleta"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>Este martes alrededor de las 16:15 horas la polic\u00eda alertada acude a San Mart\u00edn y Joaqu\u00edn V. Gonz\u00e1lez donde por razones que se tratan de establecer colision\u00f3 autom\u00f3vil conducido por masculino de 28 a\u00f1os de edad, contra motocicleta conducida por joven de 16 a\u00f1os de edad.&nbsp;<\/p>\n\n\n\n<p>El joven que circulaba en la motocicleta presenta traumatismos sin riesgo de vida.&nbsp;<\/p>\n\n\n\n<p>Interviene UFI 11 San Pedro.-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes alrededor de las 16:15 horas la polic\u00eda alertada acude a San Mart\u00edn y Joaqu\u00edn V. Gonz\u00e1lez donde por razones que se tratan de establecer colision\u00f3 autom\u00f3vil conducido por masculino de 28 a\u00f1os de edad, contra motocicleta conducida por joven de 16 a\u00f1os de edad.&nbsp; El joven que circulaba en la motocicleta presenta traumatismos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":78843,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,103],"tags":[],"class_list":["post-93892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","category-policiales-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/08\/0.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-oqo","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/93892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=93892"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/93892\/revisions"}],"predecessor-version":[{"id":93893,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/93892\/revisions\/93893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/78843"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=93892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=93892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=93892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}