{"id":87583,"date":"2021-02-12T10:14:00","date_gmt":"2021-02-12T13:14:00","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=87583"},"modified":"2021-02-12T10:14:04","modified_gmt":"2021-02-12T13:14:04","slug":"campana-apunalada-por-su-propio-hijo-se-traslado-ensangrentada-hasta-la-ddi","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/campana-apunalada-por-su-propio-hijo-se-traslado-ensangrentada-hasta-la-ddi\/","title":{"rendered":"CAMPANA | Apu\u00f1alada por su propio hijo, se traslad\u00f3 ensangrentada hasta la DDI"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>El hecho se origin\u00f3 luego de una pelea familiar en una vivienda ubicada la calle Almirante Brown al 300, donde el joven la atac\u00f3 repetidas veces con un arma blanca. Same efectu\u00f3 el traslado hacia el hospital municipal, donde actualmente se encuentra internada.<\/p>\n\n\n\n<p>En medio de las fuertes lluvias que caracterizaron las primeras horas de la tarde en la jornada de ayer, vecinos de la calle Almirante Brown oyeron gritos provenientes de la casa cercana a la esquina con 25 de Mayo, luego de lo cual descubrieron horrorizados que una mujer de unos 50 a\u00f1os de edad acababa de ser atacada ferozmente con un arma cortante por su hijo, al parecer producto de una fuerte discusi\u00f3n.<\/p>\n\n\n\n<p>Al parecer el hombre, de unos 35 a\u00f1os de edad y un pasado complejo en cuanto a su relaci\u00f3n con el resto de la familia, le habr\u00eda proporcionado alrededor de una decena de pu\u00f1aladas. Tal fue la brutalidad del ataque, que sus efectos pod\u00edan observarse incluso en las manchas de sangre esparcidas por la vereda y la misma vivienda.<\/p>\n\n\n\n<p>Si bien miembros del personal de los servicios de emergencia ya se dirig\u00edan al lugar para brindarle asistencia la misma mujer, a pesar de una considerable p\u00e9rdida de sangre, logr\u00f3 acercarse por su cuenta a la DDI Z\u00e1rate-Campana, encontr\u00e1ndose \u00e9sta a unas pocas cuadras del hecho (25 de Mayo 659).<\/p>\n\n\n\n<p>Como resultado, el hijo fue inmediatamente detenido por los mismos oficiales de la DDI, mientras que un m\u00f3vil de Same se encarg\u00f3 de trasladar de urgencia a la mujer en direcci\u00f3n al Hospital Municipal San Jos\u00e9, donde acab\u00f3 siendo intervenida dada su grave condici\u00f3n.<\/p>\n\n\n\n<p>Producto del siniestro, actualmente pesa sobre el hijo una causa penal bajo la car\u00e1tula de \u201cTentativa de Homicidio\u201d, en manos del Fiscal Mat\u00edas Ferreir\u00f3s de la Unidad Funcional de Instrucci\u00f3n N\u00b02.<\/p>\n\n\n\n<p>Se espera que hoy a las 9 de la ma\u00f1ana los m\u00e9dicos den el primer parte respecto al estado en el que se encuentra la v\u00edctima, de modo que familiares y vecinos puedan tener m\u00e1s informaci\u00f3n respecto a su salud y m\u00e1s detalles respecto a lo ocurrido.<\/p>\n\n\n\n<p>Fuente: <a href=\"https:\/\/www.campananoticias.com\/noticia\/65939\/apualada-por-su-propio-hijo-se-traslad-ensangrentada-hasta-la-ddi\">Campana Noticias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hecho se origin\u00f3 luego de una pelea familiar en una vivienda ubicada la calle Almirante Brown al 300, donde el joven la atac\u00f3 repetidas veces con un arma blanca. Same efectu\u00f3 el traslado hacia el hospital municipal, donde actualmente se encuentra internada. En medio de las fuertes lluvias que caracterizaron las primeras horas de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":87584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[621],"tags":[2126,1759,686],"class_list":["post-87583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales","tag-apunalada-por-su-propio-hijo","tag-bueno-aires","tag-campana-2"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/02\/20210212012958.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-mMD","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/87583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=87583"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/87583\/revisions"}],"predecessor-version":[{"id":87585,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/87583\/revisions\/87585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/87584"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=87583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=87583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=87583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}