{"id":82991,"date":"2020-11-01T16:12:12","date_gmt":"2020-11-01T19:12:12","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=82991"},"modified":"2020-11-01T18:47:39","modified_gmt":"2020-11-01T21:47:39","slug":"un-automovil-colisiono-a-una-moto-en-al-que-iban-dos-mujeres-y-se-dieron-a-la-fuga","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/un-automovil-colisiono-a-una-moto-en-al-que-iban-dos-mujeres-y-se-dieron-a-la-fuga\/","title":{"rendered":"Un autom\u00f3vil colisiono a una moto en al que iban dos mujeres y se dieron a la fuga"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>En la tarde de hoy ocurri\u00f3 un accidente de transito donde un autom\u00f3vil colision\u00f3 a una moto con dos ocupantes y se dio a la fuga.<\/p>\n\n\n\n<p>Pasado el mediod\u00eda de este domingo ocurri\u00f3 un accidente de tr\u00e1nsito en la esquina de Belgrano y Davila donde una moto en la que circulaban dos mujeres mayores de edad fue colisionada desde atr\u00e1s por un autom\u00f3vil Ford Escort Blanco&nbsp; que se dio a la fuga r\u00e1pidamente por Lavalle hacia el fondo el lado de 11 de septiembre.<\/p>\n\n\n\n<p>El autom\u00f3vil con el paragolpe roto fue perseguido por un testigo que vio el accidente pero no pudo darle alcance.<\/p>\n\n\n\n<p>Las dos mujeres fueron trasladadas al nosocomio local pero afortunadamente no sufrieron heridas de consideraci\u00f3n, quedando en observaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-embed-facebook wp-block-embed is-type-rich is-provider-gestor-del-servicio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/eldiario.desanpedro\/videos\/824588958082864\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En la tarde de hoy ocurri\u00f3 un accidente de transito donde un autom\u00f3vil colision\u00f3 a una moto con dos ocupantes y se dio a la fuga. Pasado el mediod\u00eda de este domingo ocurri\u00f3 un accidente de tr\u00e1nsito en la esquina de Belgrano y Davila donde una moto en la que circulaban dos mujeres mayores de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":82996,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[50,101,2],"tags":[197,33,95],"class_list":["post-82991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-interes-general-locales","category-locales","tag-buenos-aires","tag-locales","tag-policiales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/11\/Sin-titulo-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-lAz","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/82991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=82991"}],"version-history":[{"count":2,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/82991\/revisions"}],"predecessor-version":[{"id":82997,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/82991\/revisions\/82997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/82996"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=82991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=82991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=82991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}