{"id":78863,"date":"2020-08-04T10:28:16","date_gmt":"2020-08-04T13:28:16","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=78863"},"modified":"2020-08-04T10:28:20","modified_gmt":"2020-08-04T13:28:20","slug":"ife-calendario-del-tercer-pago","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/ife-calendario-del-tercer-pago\/","title":{"rendered":"IFE: Calendario del tercer pago"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p><em>La ANSES informa que,<strong>&nbsp;a partir del 10 de agosto<\/strong>, comenzar\u00e1 el pago del&nbsp;<\/em>Ingreso Familiar de Emergencia (IFE)<em>&nbsp;de 10.000 pesos junto con el cronograma de la Asignaci\u00f3n Universal por Hijo (AUH):<\/em><\/p>\n\n\n\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Lunes 10 de agosto: documentos terminados en 0.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Martes 11 de agosto: documentos terminados en 1.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Mi\u00e9rcoles 12 de agosto: documentos terminados en 2.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Jueves 13 de agosto: documentos terminados en 3.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Viernes 14 de agosto: documentos terminados en 4.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Martes 18 de agosto: documentos terminados en 5.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Mi\u00e9rcoles 19 de agosto: documentos terminados en 6.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Jueves 20 de agosto: documentos terminados en 7.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Viernes 21 de agosto: documentos terminados en 8.<br>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Lunes 24 de agosto: documentos terminados en 9.<\/p>\n\n\n\n<p><em>Asimismo,&nbsp;<\/em><strong>desde el 25 de agosto<\/strong>, la ANSES empezar\u00e1 a abonar el&nbsp;IFE a los restantes beneficiarios que validaron su Clave Bancaria Uniforme (CBU) en el aplicativo del sitio web del organismo.<\/p>\n\n\n\n<p>De esta manera, las fechas de pago ser\u00e1n a raz\u00f3n de&nbsp;<strong>dos d\u00edas h\u00e1biles por n\u00famero de terminaci\u00f3n de DNI<\/strong>; esto significa que se pagar\u00e1 el IFE a aproximadamente 300.000 personas por d\u00eda. As\u00ed se mantendr\u00e1 un cronograma de pago espaciado para cuidar la salud de los beneficiarios.&nbsp;<\/p>\n\n\n\n<p>En tanto,quienes perciban este bono deben ingresar a<strong>&nbsp;<a href=\"http:\/\/www.anses.gob.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.anses.gob.ar<\/a><\/strong>, secci\u00f3n&nbsp;<em>Ingreso Familiar de Emergencia<\/em>, para consultar la fecha de cobro.<\/p>\n\n\n\n<p>El IFE est\u00e1 destinado a cuidar en materia econ\u00f3mica y social a las familias de los sectores m\u00e1s vulnerables que se ven afectadas por la emergencia sanitaria creada por el Coronavirus (COVID19). El bono volver\u00e1 a<em>&nbsp;<\/em><em>llegar a casi 9 millones de personas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ANSES informa que,&nbsp;a partir del 10 de agosto, comenzar\u00e1 el pago del&nbsp;Ingreso Familiar de Emergencia (IFE)&nbsp;de 10.000 pesos junto con el cronograma de la Asignaci\u00f3n Universal por Hijo (AUH): \u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Lunes 10 de agosto: documentos terminados en 0.\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Martes 11 de agosto: documentos terminados en 1.\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Mi\u00e9rcoles 12 de agosto: documentos terminados en 2.\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Jueves 13 de agosto: [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":77593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[101,2],"tags":[197,696,33],"class_list":["post-78863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-general-locales","category-locales","tag-buenos-aires","tag-interes-general","tag-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/07\/ife.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-kvZ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/78863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=78863"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/78863\/revisions"}],"predecessor-version":[{"id":78864,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/78863\/revisions\/78864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/77593"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=78863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=78863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=78863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}