{"id":76238,"date":"2020-06-20T11:02:13","date_gmt":"2020-06-20T14:02:13","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=76238"},"modified":"2020-06-20T11:02:17","modified_gmt":"2020-06-20T14:02:17","slug":"un-aprehendido-por-herir-de-dos-disparos-a-un-joven","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/un-aprehendido-por-herir-de-dos-disparos-a-un-joven\/","title":{"rendered":"Un aprehendido por herir de dos disparos a un joven"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>Este s\u00e1bado se recibi\u00f3 la denuncia de una mujer mayor de edad quien se encontraba en su domicilio ubicado en Las Provincias al 2400 junto a su hijo de 17 a\u00f1os, momento que masculino se presenta en el lugar acus\u00e1ndolo de ladr\u00f3n y sin m\u00e1s&nbsp; extrae un arma de fuego y efectu\u00f3 dos disparos impactando en pierna y brazo izquierdo del menor, lesiones sin riesgo de vida.<\/p>\n\n\n\n<p>Posteriormente tras averiguaciones practicadas por personal GTO se establece quien habr\u00eda sido el autor del hecho, por lo que en Lucio Mansilla sin n\u00famero se logra su aprehensi\u00f3n, siendo este masculino mayor de edad, quien es trasladado a comisar\u00eda de San Pedro, sin lograr el secuestro del arma de fuego utilizada. Intervenci\u00f3n UFI 5 San Pedro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado se recibi\u00f3 la denuncia de una mujer mayor de edad quien se encontraba en su domicilio ubicado en Las Provincias al 2400 junto a su hijo de 17 a\u00f1os, momento que masculino se presenta en el lugar acus\u00e1ndolo de ladr\u00f3n y sin m\u00e1s&nbsp; extrae un arma de fuego y efectu\u00f3 dos disparos impactando [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":76177,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,103],"tags":[33,95],"class_list":["post-76238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","category-policiales-locales","tag-locales","tag-policiales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/20200619_132318-scaled.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-jPE","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/76238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=76238"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/76238\/revisions"}],"predecessor-version":[{"id":76239,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/76238\/revisions\/76239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/76177"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=76238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=76238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=76238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}