{"id":76234,"date":"2020-06-19T22:35:38","date_gmt":"2020-06-20T01:35:38","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=76234"},"modified":"2020-06-19T22:41:18","modified_gmt":"2020-06-20T01:41:18","slug":"tras-la-informacion-de-los-nuevos-casos-se-envian-tres-nuevas-muestras","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/tras-la-informacion-de-los-nuevos-casos-se-envian-tres-nuevas-muestras\/","title":{"rendered":"Tras la informaci\u00f3n de los nuevos casos se env\u00edan tres nuevas muestras"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>La Secretar\u00eda de Salud de la Municipalidad de San Pedro informa que se recibieron los resultados de las muestras enviadas ayer.<\/p>\n\n\n\n<p>11 de ellas tuvieron RESULTADO NEGATIVO y 2 fueron recibidas con RESULTADO POSITIVO.<\/p>\n\n\n\n<p>En el d\u00eda de hoy se enviaron tres muestras. Una de ellas pertenece al hombre de 22 a\u00f1os que dio positivo en el testeo en una empresa automotriz de Z\u00e1rate al que se realiza el segumiento. Las otras dos pertenecen a un hombre de 32 a\u00f1os y una mujer de 43 a\u00f1os.<\/p>\n\n\n\n<p>Se encuentran aisladas 140 personas (el dato ser\u00e1 actualizado con precisi\u00f3n en el d\u00eda de ma\u00f1ana por lo reciente del arribo de los resultados)<\/p>\n\n\n\n<p>Nuevas muestras enviadas: 3<br>Muestras Pendientes: 3<br>Nuevas muestras negativas: 11<br>Nuevos Casos Positivos: 2<br>Total de muestras negativas: 211<\/p>\n\n\n\n<p>Se recuerda que, ante s\u00edntomas de tos seca, fiebre y dolor de garganta y la probabilidad de haber estado en contacto con enfermos o viajeros llegados desde las zonas transmisi\u00f3n local o comunitaria se puede llamar al 148 o 107.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"992\" data-attachment-id=\"76235\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/tras-la-informacion-de-los-nuevos-casos-se-envian-tres-nuevas-muestras\/whatsapp-image-2020-06-19-at-22-28-51\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51.jpeg\" data-orig-size=\"1280,1240\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2020-06-19 at 22.28.51\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51-1024x992.jpeg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51-1024x992.jpeg\" alt=\"\" class=\"wp-image-76235 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51-1024x992.jpeg 1024w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51-300x291.jpeg 300w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51-768x744.jpeg 768w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/WhatsApp-Image-2020-06-19-at-22.28.51.jpeg 1280w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/992;\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Salud de la Municipalidad de San Pedro informa que se recibieron los resultados de las muestras enviadas ayer. 11 de ellas tuvieron RESULTADO NEGATIVO y 2 fueron recibidas con RESULTADO POSITIVO. En el d\u00eda de hoy se enviaron tres muestras. Una de ellas pertenece al hombre de 22 a\u00f1os que dio positivo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":75797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[50,101,2],"tags":[808,33],"class_list":["post-76234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-interes-general-locales","category-locales","tag-coronavirus","tag-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2020\/06\/0-2-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-jPA","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/76234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=76234"}],"version-history":[{"count":2,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/76234\/revisions"}],"predecessor-version":[{"id":76237,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/76234\/revisions\/76237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/75797"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=76234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=76234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=76234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}