{"id":65023,"date":"2019-12-03T10:59:01","date_gmt":"2019-12-03T13:59:01","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=65023"},"modified":"2019-12-03T11:59:35","modified_gmt":"2019-12-03T14:59:35","slug":"se-denuncio-que-en-chivilcoy-al-300-se-maltratarian-a-personas-de-tercera-edad-que-se-encuentran-internadas","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/se-denuncio-que-en-chivilcoy-al-300-se-maltratarian-a-personas-de-tercera-edad-que-se-encuentran-internadas\/","title":{"rendered":"Se denunci\u00f3 que en Chivilcoy al 300 se maltratar\u00edan a personas de tercera edad que se encuentran internadas"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>La denuncia se radic\u00f3 este lunes en la comisaria local pero, d\u00edas atr\u00e1s, Diego Lafalce, encargado de inspeccionar geri\u00e1tricos en conjunto con servicio de Desarrollo Humano, se hicieron presentes en el lugar para constatar el hecho pero no los dejaron ingresar, el propietario manifest\u00f3 que , \u00bb en este lugar solo hay departamentos para alquilar\u00bb.<\/p>\n\n\n\n<p> El d\u00eda viernes 29 de noviembre del corriente a\u00f1o, una mujer de 56 a\u00f1os de edad, es noticiada por integrantes de Desarrollo Humano de Municipio de San Pedro, que a ra\u00edz de una denuncia an\u00f3nima,  se constituyen a domicilio sito en calle Chivilcoy al 300, donde se maltratar\u00eda a personas de la 3ra. edad,  entre ellas su progenitora (81), las cuales se encontrarian internadas en el mismo.<\/p>\n\n\n\n<p>La mujer radica su denuncia este lunes donde cuenta que hace algunos a\u00f1os su madre, puso como apoderados a pareja conocida por esta,  ya que era su gente de confianza y les alquilaba un cuarto para vivir. Motivo en la fecha previamente habi\u00e9ndose constituido en esta ciudad, constata por medio de Anses y Pami, que su madre pose\u00eda una deuda \u00a0por la suma de $500.000  <\/p>\n\n\n\n<p>Que por dichos de personal de Desarrollo Humano, su madre se encontrar\u00eda en estado de abandono y desnutrici\u00f3n.<\/p>\n\n\n\n<p>Esta ma\u00f1ana dialogamos con Diego Lafalce, encargado del \u00e1rea de Inspecci\u00f3n de Geri\u00e1tricos de la Secretaria de Salud de San Pedro, quien nos explico su intervenci\u00f3n en el caso, \u00bb el d\u00eda 7 de noviembre me avisa Desarrollo Humano que recibieron una denuncia anonima que en ese lugar se encontrarian personas de tercera edad a quienes estarian maltratando, inmediatamente les digo vamos a verificar, a constatar el domicilio\u00bb.<\/p>\n\n\n\n<p>\u00abCuando llegamos  el due\u00f1o manifiesta que alquila habitaciones, no nos permite ingresar a inspeccionar,  es algo privado, no tenemos esa facultad para actuar\u00bb<\/p>\n\n\n\n<p>\u00abDe esta manera es que Desarrollo Humano se encarga de constatar a un familiar y contarle la situaci\u00f3n para que saque a la persona de all\u00ed, quienes le piden a la persona que radique una denuncia correspondiente  para realizar una investigaci\u00f3n judicial\u00bb<\/p>\n\n\n\n<p>Lafalce adem\u00e1s hizo un pedido a conciencia, \u00bb por favor  no lleven a sus familiares a lugares que no est\u00e1n habilitados, si son privados es dif\u00edcil para nosotros investigar , nos lleva m\u00e1s tiempo inspeccionarlo\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La denuncia se radic\u00f3 este lunes en la comisaria local pero, d\u00edas atr\u00e1s, Diego Lafalce, encargado de inspeccionar geri\u00e1tricos en conjunto con servicio de Desarrollo Humano, se hicieron presentes en el lugar para constatar el hecho pero no los dejaron ingresar, el propietario manifest\u00f3 que , \u00bb en este lugar solo hay departamentos para alquilar\u00bb. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":65034,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[50,2,103],"tags":[],"class_list":["post-65023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-locales","category-policiales-locales"],"aioseo_notices":[],"gutentor_comment":2,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/12\/PicsArt_12-03-10.55.50-e1575381482815.png","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-gUL","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/65023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=65023"}],"version-history":[{"count":2,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/65023\/revisions"}],"predecessor-version":[{"id":65063,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/65023\/revisions\/65063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/65034"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=65023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=65023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=65023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}