{"id":6406,"date":"2016-07-26T19:25:40","date_gmt":"2016-07-26T22:25:40","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=6406"},"modified":"2016-07-26T19:25:40","modified_gmt":"2016-07-26T22:25:40","slug":"gestiones-para-finalizar-las-obras-de-gas-de-santa-lucia-y-pueblo-doyle","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/gestiones-para-finalizar-las-obras-de-gas-de-santa-lucia-y-pueblo-doyle\/","title":{"rendered":"Gestiones para finalizar las obras de gas de Santa Luc\u00eda y Pueblo Doyle"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nEn la jornada de este martes el intendente Salazar, junto con el secretario de Obras y Servicios P\u00fablicos, Jorge Ponzio, y el director del Planeamiento, Ing. Hugo D\u00edaz, realizaron las gestiones en el organismo provincial, con el objetivo de que el gas llegue a las localidades.<br \/>\nYa ha sido confirmado que este a\u00f1o el tendido se har\u00e1 en R\u00edo Tala y se espera lograr que el a\u00f1o que viene se llegue a Santa Luc\u00eda y Pueblo Doyle.<br \/>\n\u201cEstuvimos en BAGSA (Buenos Aires Gas) con el ingeniero Daniel Herbalejo (gerente de Distribuci\u00f3n)\u201d, manifest\u00f3 el Salazar, consultado sobre el encuentro en la capital de la Provincia. Al tiempo que confirm\u00f3: \u201cEst\u00e1 dentro del presupuesto de este a\u00f1o el tendido de gas domiciliario para R\u00edo Tala\u201d.<br \/>\nAl tiempo, asegur\u00f3 que pidieron que se incluya para el presupuesto del a\u00f1o pr\u00f3ximo \u201clo mismo para Santa Luc\u00eda y Doyle\u201d. Y no descart\u00f3 la posibilidad para Gdor. Castro, pero desde el organismo aseguraron que la posibilidad es un poco m\u00e1s lejana. Sin embargo, el mandatario aclar\u00f3 que seguir\u00e1n trabajando para que se concrete.<br \/>\nCabe recordar que, durante la gesti\u00f3n Guacone, se iniciaron las obras que llegaron a cercan\u00edas a la localidad de Santa Luc\u00eda, pero nunca se concret\u00f3 la tercera etapa, o sea la red de tendido y extensi\u00f3n para que llegue a cada uno de los hogares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la jornada de este martes el intendente Salazar, junto con el secretario de Obras y Servicios P\u00fablicos, Jorge Ponzio, y el director del Planeamiento, Ing. Hugo D\u00edaz, realizaron las gestiones en el organismo provincial, con el objetivo de que el gas llegue a las localidades. Ya ha sido confirmado que este a\u00f1o el tendido [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6407,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[101,2],"tags":[],"class_list":["post-6406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-general-locales","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2016\/07\/gas-santa-lucia.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-1Fk","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/6406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=6406"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/6406\/revisions"}],"predecessor-version":[{"id":6408,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/6406\/revisions\/6408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/6407"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=6406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=6406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=6406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}