{"id":6392,"date":"2016-07-26T19:05:44","date_gmt":"2016-07-26T22:05:44","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=6392"},"modified":"2016-07-26T19:05:44","modified_gmt":"2016-07-26T22:05:44","slug":"productores-de-isla-de-ramallo-san-pedro-baradero-zarate-y-tigre-se-reunen-para-generar-nuevas-formas-de-organizacion","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/productores-de-isla-de-ramallo-san-pedro-baradero-zarate-y-tigre-se-reunen-para-generar-nuevas-formas-de-organizacion\/","title":{"rendered":"Productores de isla de Ramallo, San Pedro, Baradero, Z\u00e1rate y Tigre se re\u00fanen para generar nuevas formas de organizaci\u00f3n"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nLa Oficina de Desarrollo de Baradero, acompa\u00f1ada por Nancy Coixet, promotora asesora de Cambio Rural, Angel Mi\u00f1o y Hugo S\u00e1nchez, presidente y secretario de la Asociaci\u00f3n de Pescadores Artesanales de San Pedro, participaron de dicha reuni\u00f3n, llevada a cabo en el Club de Pescadores de Baradero.<br \/>\nEn el encuentro se hicieron presentes productores de isla de las ciudades de Ramallo, San Pedro, Baradero, Z\u00e1rate y Tigre para discutir sobre una forma organizativa que los represente a todos y se lleg\u00f3 a la conclusi\u00f3n de comenzar a conformar una Federaci\u00f3n de Isle\u00f1os que abarque toda la zona del Delta, tanto de la provincia de Entre R\u00edos como de Buenos Aires.<br \/>\nLa finalidad de dicha federaci\u00f3n es erradicar los agroqu\u00edmicos de la zona del Delta; direccionar y fortalecer la producci\u00f3n en mano de los isle\u00f1os, solicitar la tenencia de la tierra de quienes hace a\u00f1os viven en territorio del Delta y realizar legislaciones a favor de los isle\u00f1os.<br \/>\nEl INTA acompa\u00f1ar\u00eda dicha propuesta a trav\u00e9s de asistencia t\u00e9cnica desde la investigaci\u00f3n y la extensi\u00f3n para las diferentes zonas del Delta, forestaci\u00f3n, pesca, mimbrer\u00eda, etc. La pr\u00f3xima reuni\u00f3n se llevar\u00e1 a cabo el d\u00eda 6 de agosto en el mismo lugar, Club de Pescadores Baradero, a las 10.00. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Oficina de Desarrollo de Baradero, acompa\u00f1ada por Nancy Coixet, promotora asesora de Cambio Rural, Angel Mi\u00f1o y Hugo S\u00e1nchez, presidente y secretario de la Asociaci\u00f3n de Pescadores Artesanales de San Pedro, participaron de dicha reuni\u00f3n, llevada a cabo en el Club de Pescadores de Baradero. En el encuentro se hicieron presentes productores de isla [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6393,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[101,2],"tags":[],"class_list":["post-6392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-general-locales","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2016\/07\/collage_pescadores-1024x576.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-1F6","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/6392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=6392"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/6392\/revisions"}],"predecessor-version":[{"id":6394,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/6392\/revisions\/6394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/6393"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=6392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=6392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=6392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}