{"id":62991,"date":"2019-10-30T11:18:12","date_gmt":"2019-10-30T14:18:12","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=62991"},"modified":"2019-10-30T11:18:16","modified_gmt":"2019-10-30T14:18:16","slug":"provincia-cicop-le-pidio-a-kicillof-detener-el-deterioro-del-sistema-de-salud-publica-en-la-provincia","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/provincia-cicop-le-pidio-a-kicillof-detener-el-deterioro-del-sistema-de-salud-publica-en-la-provincia\/","title":{"rendered":"PROVINCIA | Cicop le pidi\u00f3 a Kicillof \u00abdetener el deterioro\u00bb del sistema de salud p\u00fablica en la provincia"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>El gremio que nuclea a trabajadores y profesionales de la salud bonaerenses, Cicop, lanz\u00f3 un comunicado sobre los resultados de las elecciones del domingo para continuar con sus reclamos. En ese sentido, le solicitaron al gobernador electo, Axel Kicillof, que se comprometa a brindar soluciones ante el mal estado en que se encuestran los hospitales en la provincia.<\/p>\n\n\n\n<p>Entonces, el sindicato\u00a0se refiri\u00f3 a \u00abquienes tendr\u00e1n la responsabilidad de conducir los destinos de la provincia de Buenos Aires a partir del pr\u00f3ximo 10 de diciembre\u00bb y expresaron:\u00a0<strong>\u201cInstamos a las pr\u00f3ximas autoridades a comprometerse en acciones que tiendan a detener el deterioro en que se encuentra el \u00e1rea, bregando por pol\u00edticas que modifiquen sustancialmente el cuadro actual porque venimos de a\u00f1os de desidia y desinversi\u00f3n, que incluye no s\u00f3lo a la gesti\u00f3n a\u00fan vigente\u00bb.<\/strong><\/p>\n\n\n\n<p>\u00abEntendemos que la salud debe ser considerada como un derecho y no como un bien de mercado; destacar a las y los trabajadores como fundamentales en el funcionamiento del sistema sanitario; dotar de insumos e infraestructura acordes para una asistencia digna; promover el fortalecimiento del primer nivel de atenci\u00f3n como una instancia imprescindible en el abordaje de los problemas de salud; y desarrollar la producci\u00f3n p\u00fablica de medicamentos\u00bb, a\u00f1adieron.<\/p>\n\n\n\n<p>Fuente: Ramallo Informa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gremio que nuclea a trabajadores y profesionales de la salud bonaerenses, Cicop, lanz\u00f3 un comunicado sobre los resultados de las elecciones del domingo para continuar con sus reclamos. En ese sentido, le solicitaron al gobernador electo, Axel Kicillof, que se comprometa a brindar soluciones ante el mal estado en que se encuestran los hospitales [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[621],"tags":[],"class_list":["post-62991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/10\/20191029064905_cicop.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-gnZ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/62991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=62991"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/62991\/revisions"}],"predecessor-version":[{"id":62993,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/62991\/revisions\/62993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/62992"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=62991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=62991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=62991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}