{"id":53072,"date":"2019-05-20T10:59:16","date_gmt":"2019-05-20T13:59:16","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=53072"},"modified":"2019-05-20T10:59:27","modified_gmt":"2019-05-20T13:59:27","slug":"san-nicolas-mas-de-40-mil-personas-disfrutaron-de-acercarte","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/san-nicolas-mas-de-40-mil-personas-disfrutaron-de-acercarte\/","title":{"rendered":"SAN NICOL\u00c1S: M\u00e1s de 40 mil personas disfrutaron de Acercarte"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>\n\nEl fin de semana, los nicole\u00f1os pudieron disfrutar de las actividades y propuestas gratuitas que se llevaron a cabo en la Costanera Alta de San Nicol\u00e1s en el marco del programa provincial \u201cAcercarte\u201d.<\/p>\n\n\n\n<p>Durante la tarde del s\u00e1bado y del domingo, chicos y grandes comenzaron a disfrutar de diferentes ramas de la cultura a trav\u00e9s de los talleres de pintura, cortometrajes en el cine 360 y el cine m\u00f3vil, el taller de reutilizaci\u00f3n creativa y muchas otras propuestas que acercan a los nicole\u00f1os al arte y a la cultura.<\/p>\n\n\n\n<p>Los Cazurros y los Heavysaurios fueron dos de los shows preferidos de los m\u00e1s chicos que estuvieron atentos a cada parte del espect\u00e1culo acompa\u00f1ando la actuaci\u00f3n y cantando los temas con gritos y aplausos.<\/p>\n\n\n\n<p>Como shows principales, Los Nocheros y Patricia Sosa convocaron a gran cantidad de p\u00fablico que acompa\u00f1o todos sus \u00e9xitos de dos artistas con una excelente trayectoria dentro y fuera del pa\u00eds.<\/p>\n\n\n\n<p>Por \u00faltimo, en el Teatro Municipal \u201cRafael de Aguiar\u201d Graciela Borges present\u00f3 \u201cAlquimia\u201d y Fabi\u00e1n Vena lleg\u00f3 con su obra \u201cConferencia sobre la lluvia\u201d en donde los nicole\u00f1os pudieron disfrutar de dos grandes actores<\/p>\n\n\n\n<p>Durante el fin de semana, m\u00e1s de 40 mil personas disfrutaron de un evento que tuvo propuestas para toda la familia y en un lugar con la infraestructura adecuada como es la Costanera de San Nicol\u00e1s, capaz de albergar este tipo de espect\u00e1culos. <\/p>\n\n\n\n<p>Fuente: Diario El Informante<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fin de semana, los nicole\u00f1os pudieron disfrutar de las actividades y propuestas gratuitas que se llevaron a cabo en la Costanera Alta de San Nicol\u00e1s en el marco del programa provincial \u201cAcercarte\u201d. Durante la tarde del s\u00e1bado y del domingo, chicos y grandes comenzaron a disfrutar de diferentes ramas de la cultura a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":53073,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[621],"tags":[],"class_list":["post-53072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/conmarca20153.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-dO0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/53072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=53072"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/53072\/revisions"}],"predecessor-version":[{"id":53074,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/53072\/revisions\/53074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/53073"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=53072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=53072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=53072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}