{"id":53063,"date":"2019-05-20T10:40:01","date_gmt":"2019-05-20T13:40:01","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=53063"},"modified":"2019-05-20T11:04:53","modified_gmt":"2019-05-20T14:04:53","slug":"campana-pfa-desarticulo-red-multicriminal-dedicada-al-trafico-y-comercializacion-de-drogas","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/campana-pfa-desarticulo-red-multicriminal-dedicada-al-trafico-y-comercializacion-de-drogas\/","title":{"rendered":"CAMPANA: PFA desarticul\u00f3 red multicriminal dedicada al tr\u00e1fico y comercializaci\u00f3n de drogas"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>Sus miembros principales estaban condenados y privados de su libertad, actualmente beneficiados con prisi\u00f3n domiciliaria y el uso de pulsera electr\u00f3nica. Trabajo de la Brigada con asiento en Campana de la Polic\u00eda Federal Argentina (PFA).&nbsp; <\/p>\n\n\n\n<p>\n\nLos ocho integrantes de la banda fueron detenidos por la Polic\u00eda Federal, luego de 17 allanamientos en la provincia de Buenos Aires y C\u00f3rdoba, en el marco del refuerzo en investigaci\u00f3n criminal que impulsa el Ministerio de Seguridad a cargo de Patricia Bullrich.<\/p>\n\n\n\n<p>Eran investigados desde noviembre del 2018, y se dedicaban al tr\u00e1fico y comercializaci\u00f3n de estupefacientes.&nbsp;<\/p>\n\n\n\n<p>Sus miembros principales estaban condenados y privados de su libertad, actualmente beneficiados con prisi\u00f3n domiciliaria y el uso de pulsera electr\u00f3nica.<\/p>\n\n\n\n<p>\u201cEs muy importante el esfuerzo que hacemos junto a las fuerzas federales para reforzar las tareas de inteligencia criminal. Ac\u00e1 se desmantel\u00f3 una banda importante, con personas con prisi\u00f3n domiciliaria, quien aun as\u00ed segu\u00edan delinquiendo\u201d, sostuvo la ministra Bullrich, quien instruy\u00f3 pol\u00edticas expresas a la Secretar\u00eda de Seguridad que conduce Eugenio Burzaco.<\/p>\n\n\n\n<p>En el operativo se secuestraron m\u00e1s de 35 mil dosis de marihuana, coca\u00edna, rodados, elementos de corte y pesaje, dinero en efectivo y celulares.<\/p>\n\n\n\n<p>La organizaci\u00f3n estaba integrada por narcotraficantes y chapistas, que participaban activamente acondicionando veh\u00edculos con dobles fondos para el traslado de las drogas.<\/p>\n\n\n\n<p>Tambi\u00e9n hab\u00eda personal militar, ex polic\u00edas y delincuentes comunes, que adem\u00e1s planificaban distintos robos en la modalidad \u201cescrruche\u201d y en cajeros autom\u00e1ticos.<\/p>\n\n\n\n<p>Su radio de acci\u00f3n se centraba en las localidades de Ramallo, San Nicol\u00e1s, Pergamino, Tallar de Pacheco, y la ciudad cordobesa de Villa Carlos Paz.<\/p>\n\n\n\n<p>A lo largo de la investigaci\u00f3n, se pudo comprobar la participaci\u00f3n de los delincuentes en el traslado de 100 kilos de marihuana, hecho ocurrido en enero de este a\u00f1o, cuando en la ciudad de Baradero se detect\u00f3 un veh\u00edculo acondicionado para traficar droga, la cual iba dirigida a la provincia de C\u00f3rdoba. En esa oportunidad y tras embestir con el auto a una formaci\u00f3n ferroviaria, un miembro de la banda falleci\u00f3 y el otro fue detenido.<\/p>\n\n\n\n<p>A ra\u00edz de esta situaci\u00f3n, el personal del departamento Antidrogas Centro de la PFA, continu\u00f3 las pesquisas que permitieron frustrar un nuevo traslado de drogas, para luego efectuar finalmente los 17 allanamientos y detener a los ocho involucrados: siete hombres y una mujer.<\/p>\n\n\n\n<p>Intervino el Juzgado de San Nicol\u00e1s, a cargo del Dr. Carlos Villafuerte Russo, Secretar\u00eda del Dr. Jos\u00e9 Antonio Pendino. <\/p>\n\n\n\n<p>Fuente: Campana Noticias<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"470\" height=\"163\" data-attachment-id=\"53064\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/campana-pfa-desarticulo-red-multicriminal-dedicada-al-trafico-y-comercializacion-de-drogas\/attachment\/20190518073735\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073735.jpg\" data-orig-size=\"470,163\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"20190518073735\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073735.jpg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073735.jpg\" alt=\"\" class=\"wp-image-53064 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073735.jpg 470w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073735-300x104.jpg 300w\" data-sizes=\"(max-width: 470px) 100vw, 470px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 470px; --smush-placeholder-aspect-ratio: 470\/163;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"470\" height=\"205\" data-attachment-id=\"53077\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/campana-pfa-desarticulo-red-multicriminal-dedicada-al-trafico-y-comercializacion-de-drogas\/attachment\/20190518073714\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073714.jpg\" data-orig-size=\"470,205\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"20190518073714\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073714.jpg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073714.jpg\" alt=\"\" class=\"wp-image-53077 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073714.jpg 470w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073714-300x131.jpg 300w\" data-sizes=\"(max-width: 470px) 100vw, 470px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 470px; --smush-placeholder-aspect-ratio: 470\/205;\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sus miembros principales estaban condenados y privados de su libertad, actualmente beneficiados con prisi\u00f3n domiciliaria y el uso de pulsera electr\u00f3nica. Trabajo de la Brigada con asiento en Campana de la Polic\u00eda Federal Argentina (PFA).&nbsp; Los ocho integrantes de la banda fueron detenidos por la Polic\u00eda Federal, luego de 17 allanamientos en la provincia de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":53075,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[621],"tags":[],"class_list":["post-53063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/05\/20190518073724.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-dNR","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/53063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=53063"}],"version-history":[{"count":2,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/53063\/revisions"}],"predecessor-version":[{"id":53078,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/53063\/revisions\/53078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/53075"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=53063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=53063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=53063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}