{"id":47725,"date":"2019-02-17T18:36:49","date_gmt":"2019-02-17T21:36:49","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=47725"},"modified":"2019-02-17T18:37:02","modified_gmt":"2019-02-17T21:37:02","slug":"dos-accidentes-con-dos-jovenes-en-coma","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/","title":{"rendered":"Dos accidentes con dos j\u00f3venes en coma"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p class=\"wp-block-paragraph\">Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de  establecer,  en la intersecci\u00f3n de Salta y Col\u00f3n, motocicleta 110 cc guiada por masculino de 31 a\u00f1os de edad quien colisiono contra una pickup Ford Ranger guiada por masculino de 63 a\u00f1os de edad.  Como consecuencia conductor de la moto presenta lesiones graves (trauma de cr\u00e1neo perdida conocimiento,\u00a0\u00a0fractura miembro inferior y cadera) internado en UTI hospital local quedando en coma inducido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En  los primeros minutos del domingo pasadas las 00 hs la Polic\u00eda de interviene en un accidente de transito por causas se establecen en intersecci\u00f3n de Av. 3 de Febrero y Anibal de Anton, colisionaron motocicleta 125 cc guiada por masculino de 25 a\u00f1os, y autom\u00f3vil guiado por joven de 19 a\u00f1os de edad. Como consecuencia conductor motocicleta presenta lesiones graves (traumatismo de cr\u00e1neo ,perdida de conocimiento coma inducido). internado en UTI hospital local, coma inducido. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ambos casos interviene la fiscalia de turno de San Pedro.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"498\" data-attachment-id=\"47734\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/20190216_214310\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214310.jpg\" data-orig-size=\"4032,1960\" data-comments-opened=\"1\" data-image-title=\"20190216_214310\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214310-1024x498.jpg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214310-1024x498.jpg\" alt=\"\" class=\"wp-image-47734 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214310-1024x498.jpg 1024w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214310-300x146.jpg 300w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214310-768x373.jpg 768w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/498;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"498\" data-attachment-id=\"47730\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/20190216_214253\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214253.jpg\" data-orig-size=\"4032,1960\" data-comments-opened=\"1\" data-image-title=\"20190216_214253\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214253-1024x498.jpg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214253-1024x498.jpg\" alt=\"\" class=\"wp-image-47730 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214253-1024x498.jpg 1024w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214253-300x146.jpg 300w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214253-768x373.jpg 768w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/498;\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":47732,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,103],"tags":[],"class_list":["post-47725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales","category-policiales-locales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fernando Gonzalez Bettendorff\"\/>\n\t<meta name=\"google-site-verification\" content=\"FgwjwRGGMHg0DFt89mJZywUL3A_nMHpun_ctyVNfKDs\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Diario de San Pedro | Noticias locales y regionales\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Dos accidentes con dos j\u00f3venes en coma\" \/>\n\t\t<meta property=\"og:description\" content=\"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1960\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-02-17T21:36:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-17T21:37:02+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/profile.php?id=61562291519621\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ElDiariodeSP\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Dos accidentes con dos j\u00f3venes en coma\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ElDiariodeSP\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2023\/04\/cropped-favicon.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#blogposting\",\"name\":\"Dos accidentes con dos j\\u00f3venes en coma\",\"headline\":\"Dos accidentes con dos j\\u00f3venes en coma\",\"author\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/20190216_214213.jpg\",\"width\":4032,\"height\":1960},\"datePublished\":\"2019-02-17T18:36:49-03:00\",\"dateModified\":\"2019-02-17T18:37:02-03:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#webpage\"},\"articleSection\":\"Locales, Policiales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/#listItem\",\"name\":\"Locales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/#listItem\",\"position\":2,\"name\":\"Locales\",\"item\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/policiales-locales\\\/#listItem\",\"name\":\"Policiales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/policiales-locales\\\/#listItem\",\"position\":3,\"name\":\"Policiales\",\"item\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/policiales-locales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#listItem\",\"name\":\"Dos accidentes con dos j\\u00f3venes en coma\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/#listItem\",\"name\":\"Locales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#listItem\",\"position\":4,\"name\":\"Dos accidentes con dos j\\u00f3venes en coma\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/policiales-locales\\\/#listItem\",\"name\":\"Policiales\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#organization\",\"name\":\"El Diario de San Pedro\",\"description\":\"Medio digital de noticias de San Pedro y la regi\\u00f3n, con cobertura local en pol\\u00edtica, policiales, sociedad, deportes y servicios.\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/El-Diario.jpg\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/profile.php?id=61562291519621\",\"https:\\\/\\\/x.com\\\/ElDiariodeSP\",\"https:\\\/\\\/www.instagram.com\\\/eldiariosanpedro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@eldiariosanpedro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/\",\"name\":\"Fernando Gonzalez Bettendorff\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#webpage\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/\",\"name\":\"Dos accidentes con dos j\\u00f3venes en coma\",\"description\":\"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\\u00f3n de Salta y Col\\u00f3n,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/20190216_214213.jpg\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#mainImage\",\"width\":4032,\"height\":1960},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/dos-accidentes-con-dos-jovenes-en-coma\\\/#mainImage\"},\"datePublished\":\"2019-02-17T18:36:49-03:00\",\"dateModified\":\"2019-02-17T18:37:02-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/\",\"name\":\"El Diario de San Pedro | Noticias locales y regionales\",\"alternateName\":\"El Diario de San Pedro\",\"description\":\"Noticias de San Pedro y la regi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Dos accidentes con dos j\u00f3venes en coma","description":"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,","canonical_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"FgwjwRGGMHg0DFt89mJZywUL3A_nMHpun_ctyVNfKDs","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#blogposting","name":"Dos accidentes con dos j\u00f3venes en coma","headline":"Dos accidentes con dos j\u00f3venes en coma","author":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author"},"publisher":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg","width":4032,"height":1960},"datePublished":"2019-02-17T18:36:49-03:00","dateModified":"2019-02-17T18:37:02-03:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#webpage"},"isPartOf":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#webpage"},"articleSection":"Locales, Policiales"},{"@type":"BreadcrumbList","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio#listItem","position":1,"name":"Home","item":"https:\/\/eldiariodesanpedro.com.ar\/sitio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/#listItem","name":"Locales"}},{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/#listItem","position":2,"name":"Locales","item":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/policiales-locales\/#listItem","name":"Policiales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/policiales-locales\/#listItem","position":3,"name":"Policiales","item":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/policiales-locales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#listItem","name":"Dos accidentes con dos j\u00f3venes en coma"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/#listItem","name":"Locales"}},{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#listItem","position":4,"name":"Dos accidentes con dos j\u00f3venes en coma","previousItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/policiales-locales\/#listItem","name":"Policiales"}}]},{"@type":"Organization","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#organization","name":"El Diario de San Pedro","description":"Medio digital de noticias de San Pedro y la regi\u00f3n, con cobertura local en pol\u00edtica, policiales, sociedad, deportes y servicios.","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/","logo":{"@type":"ImageObject","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2026\/01\/El-Diario.jpg","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/profile.php?id=61562291519621","https:\/\/x.com\/ElDiariodeSP","https:\/\/www.instagram.com\/eldiariosanpedro\/","https:\/\/www.youtube.com\/@eldiariosanpedro"]},{"@type":"Person","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/","name":"Fernando Gonzalez Bettendorff"},{"@type":"WebPage","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#webpage","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/","name":"Dos accidentes con dos j\u00f3venes en coma","description":"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#website"},"breadcrumb":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#breadcrumblist"},"author":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author"},"creator":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#mainImage","width":4032,"height":1960},"primaryImageOfPage":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/#mainImage"},"datePublished":"2019-02-17T18:36:49-03:00","dateModified":"2019-02-17T18:37:02-03:00"},{"@type":"WebSite","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#website","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/","name":"El Diario de San Pedro | Noticias locales y regionales","alternateName":"El Diario de San Pedro","description":"Noticias de San Pedro y la regi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Diario de San Pedro | Noticias locales y regionales","og:type":"article","og:title":"Dos accidentes con dos j\u00f3venes en coma","og:description":"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,","og:url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/","og:image":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg","og:image:secure_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg","og:image:width":4032,"og:image:height":1960,"article:published_time":"2019-02-17T21:36:49+00:00","article:modified_time":"2019-02-17T21:37:02+00:00","article:publisher":"https:\/\/facebook.com\/profile.php?id=61562291519621","twitter:card":"summary_large_image","twitter:site":"@ElDiariodeSP","twitter:title":"Dos accidentes con dos j\u00f3venes en coma","twitter:description":"Dos graves accidentes ocurrieron este sabado y domingo en las primeras horas donde dos j\u00f3venes fueron internados en terapia intensiva con coma inducido. Este sabado promediando las 21 hs se produjo el primero de los dos graves accidentes de transito, donde por causas que se tratan de establecer, en la intersecci\u00f3n de Salta y Col\u00f3n,","twitter:creator":"@ElDiariodeSP","twitter:image":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2023\/04\/cropped-favicon.png"},"aioseo_meta_data":{"post_id":"47725","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-07-16 12:19:49","updated":"2025-07-16 12:19:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/\" title=\"Locales\">Locales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/policiales-locales\/\" title=\"Policiales\">Policiales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDos accidentes con dos j\u00f3venes en coma\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio"},{"label":"Locales","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/"},{"label":"Policiales","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/policiales-locales\/"},{"label":"Dos accidentes con dos j\u00f3venes en coma","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/dos-accidentes-con-dos-jovenes-en-coma\/"}],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2019\/02\/20190216_214213.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-cpL","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/47725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=47725"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/47725\/revisions"}],"predecessor-version":[{"id":47735,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/47725\/revisions\/47735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/47732"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=47725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=47725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=47725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}