{"id":30962,"date":"2018-03-28T18:22:23","date_gmt":"2018-03-28T21:22:23","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=30962"},"modified":"2018-03-28T18:22:23","modified_gmt":"2018-03-28T21:22:23","slug":"baradero-comercios-en-jaque-ya-cerraron-cuatro-locales","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/baradero-comercios-en-jaque-ya-cerraron-cuatro-locales\/","title":{"rendered":"BARADERO: Comercios en jaque: Ya cerraron cuatro locales"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nLos tarifazos de luz, gas, tasas municipales y alquiler m\u00e1s la presi\u00f3n tributaria ahogan al sector comercial que ve caer dr\u00e1sticamente el consumo.<\/p>\n<p>Si los n\u00fameros no cierran, cierran los comercios y la desocupaci\u00f3n crece. Los comerciantes ya no saben m\u00e1s que hacer para reducir sus consumos de luz y de gas. No basta con cambiar los focos bajo consumo por iluminaci\u00f3n led. El incremento de las tarifas fue alt\u00edsimo y ante un mismo consumo las boletas de luz llegaron con aumentos de hasta un 400%. Alguna despensas se privaron de vender helados en el verano para tener conectadas las heladeras. Otros comerciantes soportaron las altas temperaturas sin aire acondicionado y optaron por los ventilares al m\u00e1ximo. No les alcanz\u00f3.<\/p>\n<p>Llegaron las nuevas boletas de luz y son varios los que se quedan sentados, mirando el importe final y no lo pueden creer; piensan qu\u00e9 hacer. Algunos optan por recortar el hilo por lo m\u00e1s delgado: despedir empleados. Otros no quieren llegar a esa instancia ni tampoco a la de cerrar. Por eso reaccionaron y decidieron juntarse esta semana para firmar un petitorio a los fines de ser entregado a la intendente Fernanda Antonijevic con la intenci\u00f3n de que la funcionaria se re\u00fana con la gobernadora Mar\u00eda Eugenia Vidal a los fines de brindarles una salida a la crisis.<br \/>\nUna de las observaciones que realizaron es la alta presi\u00f3n tributaria: pagan m\u00e1s impuestos que el equivalente al consumo real de energ\u00eda.<\/p>\n<p>\u201cYa venimos complicados desde hace un tiempo y las \u00faltimas boletas que llegaron hacen que la crisis sea m\u00e1s profunda\u201d, dijo Dami\u00e1n Mori, secretario del Centro de Comercio e Industria y manifest\u00f3: \u201cMuchos comerciantes pidieron que se busquen soluciones. Algunos comerciantes ya quer\u00edan salir a cortar la ruta 9 y realizar marchas a las empresas como por ejemplo EDEN. Algo similar a lo que vivimos en el 2007. Lo que acordamos fue hacer un petitorio adjuntando firmas de los comerciantes para ser entregado a la intendenta y elevado a la gobernadora\u201d.<br \/>\nCon respecto a las boletas de luz que llegaron en la \u00faltima semana dijo que \u201chay sumas desorbitantes, hay despensas donde pagaban dos mil pesos de luz y ahora superan los diez mil\u201d.<\/p>\n<p>Mori cont\u00f3 el caso puntual de un comercio al que le llevan el pan. El local est\u00e1n ubicado cercano a las v\u00edas, en un barrio humilde: \u201cRecibieron una boleta de 10.100 pesos, la due\u00f1a estaba en estado de shock. La se\u00f1ora que hace m\u00e1s de 20 a\u00f1os tiene la despensa me dijo que ni vendiendo toda su mercader\u00eda puede vender la luz. Y se preguntaba c\u00f3mo seguir durante los pr\u00f3ximos meses si ni siquiera puede pagar la luz de este mes\u201d.<\/p>\n<p>El secretario del Centro de Comercio remarc\u00f3 que \u201clos comerciantes estamos en un encrucijada\u201d y cont\u00f3 otro caso: \u201cA un comerciante antes la luz le equival\u00eda el 7% del alquiler y hoy le representa el 100%, es decir, paga lo mismo de alquiler que de luz\u201d.<\/p>\n<p>Tambi\u00e9n se encuentran con el desalentador escenario que el consumo cay\u00f3 dr\u00e1sticamente entonces el tarifazo no lo pueden volcar a los productos porque el consumo de los clientes caer\u00eda a\u00fan m\u00e1s.<\/p>\n<p>\u201cHay rubros, como el m\u00edo que es la panader\u00eda, tenemos un doble impacto por la luz y el gas, como los gastron\u00f3micos, porque el gas tendr\u00e1 un 45% de aumento en abril. El panorama es negro, de colapso. La primera variable, que no es la mejor, es reducir personal. Queda gente en la calle. Al hacer los n\u00fameros ves que con lo que ahorr\u00e1s de tener un empleado pag\u00e1s la luz. Se piensan un mont\u00f3n de alternativas para no llegar a eso, por ejemplo, algunos decidieron trabajar desde m\u00e1s temprano para aprovechar la luz del sol y gastar menos luz. Pero llega la boleta y no pod\u00e9s respirar\u201d.<\/p>\n<p>Mori expres\u00f3: \u201cQueremos que la situaci\u00f3n sea racional. Es cierto que las tarifas estaban retra\u00eddas pero apliquemos un criterio que nos sirva a todos porque tuvimos un 40% de inflaci\u00f3n y un 400% o 500% de aumento de luz y gas. Es desproporcional para el bolsillo de la gente y de los comercios\u201d.<\/p>\n<p>A modo de soluci\u00f3n indic\u00f3 que \u201cla gobernadora tiene la capacidad de resolver esta situaci\u00f3n\u201d y ejemplific\u00f3 con otro caso de un comerciante local que paga 1.800 pesos de consumo real de luz a los que debe sumarle 2.200 de impuestos. O sea, se paga m\u00e1s de impuesto que de luz. Entiendo que el estado tiene que recaudar pero tambi\u00e9n los comercios tienen que vivir, es una convivencia entre todos para que el comercio no siga castigado. El \u00faltimo \u00edndice de recesi\u00f3n de consumo es del 8% en enero, m\u00e1s todo el 2017. Por eso en Baradero ves locales vac\u00edos, otros a punto de cerrar, en este \u00faltimo tiempo cerraron cuatro comercios. Algunos piensan m\u00e1s en poner un plazo fijo que le da m\u00e1s plata\u201d.<\/p>\n<p>Fuente: La Aut\u00e9ntica Opini\u00f3n (Edici\u00f3n gr\u00e1fica del 23\/03\/18)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los tarifazos de luz, gas, tasas municipales y alquiler m\u00e1s la presi\u00f3n tributaria ahogan al sector comercial que ve caer dr\u00e1sticamente el consumo. Si los n\u00fameros no cierran, cierran los comercios y la desocupaci\u00f3n crece. Los comerciantes ya no saben m\u00e1s que hacer para reducir sus consumos de luz y de gas. No basta con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30964,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[621],"tags":[],"class_list":["post-30962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/03\/liquidacion-total.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-83o","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/30962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=30962"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/30962\/revisions"}],"predecessor-version":[{"id":30966,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/30962\/revisions\/30966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/30964"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=30962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=30962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=30962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}