{"id":28980,"date":"2018-02-07T14:40:56","date_gmt":"2018-02-07T17:40:56","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=28980"},"modified":"2018-02-07T14:40:56","modified_gmt":"2018-02-07T17:40:56","slug":"zarate-vivo-de-milagro","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/zarate-vivo-de-milagro\/","title":{"rendered":"ZARATE: Vivo de milagro"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nAlrededor de las seis de la ma\u00f1ana de este mi\u00e9rcoles, un conductor perdi\u00f3 el control de su Toyota Etios e impact\u00f3 contra un poste de luz para luego terminar volcando. Ocurri\u00f3 frente a la planta de Toyota de Z\u00e1rate, en el desv\u00edo para tomar Ruta N\u00ba 9 sentido a Rosario.<\/p>\n<p>El hombre result\u00f3 gravemente herido y fue rescatado por el Comando Patrulla, Polic\u00eda Local y Bomberos Voluntarios de Z\u00e1rate. Una ambulancia de Semzar lo traslad\u00f3 de urgencia al Hospital Virgen del Carmen en donde ser\u00e1 tratado por un profundo corte en su cabeza, adem\u00e1s de otros golpes.<\/p>\n<p>Se desconoce si hubo un segundo veh\u00edculo involucrado o si se trat\u00f3 de una mala maniobra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alrededor de las seis de la ma\u00f1ana de este mi\u00e9rcoles, un conductor perdi\u00f3 el control de su Toyota Etios e impact\u00f3 contra un poste de luz para luego terminar volcando. Ocurri\u00f3 frente a la planta de Toyota de Z\u00e1rate, en el desv\u00edo para tomar Ruta N\u00ba 9 sentido a Rosario. El hombre result\u00f3 gravemente herido [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28981,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[621],"tags":[],"class_list":["post-28980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regionales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/02\/PAGINA-6-DOS-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-7xq","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/28980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=28980"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/28980\/revisions"}],"predecessor-version":[{"id":28982,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/28980\/revisions\/28982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/28981"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=28980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=28980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=28980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}