{"id":28462,"date":"2018-01-26T19:56:17","date_gmt":"2018-01-26T22:56:17","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=28462"},"modified":"2018-01-26T19:56:17","modified_gmt":"2018-01-26T22:56:17","slug":"salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/","title":{"rendered":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\nEl Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro.<\/p>\n<p>  Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal Cecilio Salazar recibi\u00f3 a los medios en su despacho. All\u00ed expres\u00f3 sus sensaciones ante un d\u00eda tan triste y volvi\u00f3 a criticar a la Justicia garantista que permite que los delincuentes salgan antes de lo previsto o ni siquiera est\u00e9n presos.<\/p>\n<p>  \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d, dijo Salazar. \u201cA Lillo lo conoc\u00eda, su padre es trabajador municipal\u201d.<\/p>\n<p>  \u201cHoy la ciudadan\u00eda est\u00e1 muy triste y lo menos que podemos hacer es homenajear como corresponde a este gran valor policial que perdimos\u201d.<\/p>\n<p>  Salazar remarc\u00f3 que mantuvo comunicaciones con el Ministro Ritondo y la Intendente de Baradero Fernanda Antonijevic para hablar de lo sucedido en el mediod\u00eda del jueves. <\/p>\n<p>Fuente y Gentileza: San Pedro Informa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":28467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[101,2],"tags":[],"class_list":["post-28462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-general-locales","category-locales"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fernando Gonzalez Bettendorff\"\/>\n\t<meta name=\"google-site-verification\" content=\"FgwjwRGGMHg0DFt89mJZywUL3A_nMHpun_ctyVNfKDs\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Diario de San Pedro | Noticias locales y regionales\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d\" \/>\n\t\t<meta property=\"og:description\" content=\"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1122\" \/>\n\t\t<meta property=\"og:image:height\" content=\"591\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-01-26T22:56:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-01-26T22:56:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/profile.php?id=61562291519621\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ElDiariodeSP\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@ElDiariodeSP\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2023\/04\/cropped-favicon.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#blogposting\",\"name\":\"Salazar: \\u201cEs el d\\u00eda m\\u00e1s triste desde que asumimos esta gesti\\u00f3n\\u201d\",\"headline\":\"Salazar: \\u201cEs el d\\u00eda m\\u00e1s triste desde que asumimos esta gesti\\u00f3n\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/El-Intendente-de-San-Pedro.jpg\",\"width\":1122,\"height\":591},\"datePublished\":\"2018-01-26T19:56:17-03:00\",\"dateModified\":\"2018-01-26T19:56:17-03:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#webpage\"},\"articleSection\":\"Inter\\u00e9s General, Locales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/#listItem\",\"name\":\"Locales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/#listItem\",\"position\":2,\"name\":\"Locales\",\"item\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/interes-general-locales\\\/#listItem\",\"name\":\"Inter\\u00e9s General\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/interes-general-locales\\\/#listItem\",\"position\":3,\"name\":\"Inter\\u00e9s General\",\"item\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/interes-general-locales\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#listItem\",\"name\":\"Salazar: \\u201cEs el d\\u00eda m\\u00e1s triste desde que asumimos esta gesti\\u00f3n\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/#listItem\",\"name\":\"Locales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#listItem\",\"position\":4,\"name\":\"Salazar: \\u201cEs el d\\u00eda m\\u00e1s triste desde que asumimos esta gesti\\u00f3n\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/category\\\/locales\\\/interes-general-locales\\\/#listItem\",\"name\":\"Inter\\u00e9s General\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#organization\",\"name\":\"El Diario de San Pedro\",\"description\":\"Medio digital de noticias de San Pedro y la regi\\u00f3n, con cobertura local en pol\\u00edtica, policiales, sociedad, deportes y servicios.\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/El-Diario.jpg\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/profile.php?id=61562291519621\",\"https:\\\/\\\/x.com\\\/ElDiariodeSP\",\"https:\\\/\\\/www.instagram.com\\\/eldiariosanpedro\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@eldiariosanpedro\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/\",\"name\":\"Fernando Gonzalez Bettendorff\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#webpage\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/\",\"name\":\"Salazar: \\u201cEs el d\\u00eda m\\u00e1s triste desde que asumimos esta gesti\\u00f3n\\u201d\",\"description\":\"El Intendente Municipal lament\\u00f3 la p\\u00e9rdida del agente de Polic\\u00eda Local Lillo y volvi\\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\\u00e1 siendo velado en el Sal\\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/author\\\/fernando\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/El-Intendente-de-San-Pedro.jpg\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#mainImage\",\"width\":1122,\"height\":591},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\\\/#mainImage\"},\"datePublished\":\"2018-01-26T19:56:17-03:00\",\"dateModified\":\"2018-01-26T19:56:17-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#website\",\"url\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/\",\"name\":\"El Diario de San Pedro | Noticias locales y regionales\",\"alternateName\":\"El Diario de San Pedro\",\"description\":\"Noticias de San Pedro y la regi\\u00f3n\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/eldiariodesanpedro.com.ar\\\/sitio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","description":"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal","canonical_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"FgwjwRGGMHg0DFt89mJZywUL3A_nMHpun_ctyVNfKDs","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#blogposting","name":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","headline":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","author":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author"},"publisher":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg","width":1122,"height":591},"datePublished":"2018-01-26T19:56:17-03:00","dateModified":"2018-01-26T19:56:17-03:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#webpage"},"isPartOf":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#webpage"},"articleSection":"Inter\u00e9s General, Locales"},{"@type":"BreadcrumbList","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio#listItem","position":1,"name":"Home","item":"https:\/\/eldiariodesanpedro.com.ar\/sitio","nextItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/#listItem","name":"Locales"}},{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/#listItem","position":2,"name":"Locales","item":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/interes-general-locales\/#listItem","name":"Inter\u00e9s General"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/interes-general-locales\/#listItem","position":3,"name":"Inter\u00e9s General","item":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/interes-general-locales\/","nextItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#listItem","name":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/#listItem","name":"Locales"}},{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#listItem","position":4,"name":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/interes-general-locales\/#listItem","name":"Inter\u00e9s General"}}]},{"@type":"Organization","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#organization","name":"El Diario de San Pedro","description":"Medio digital de noticias de San Pedro y la regi\u00f3n, con cobertura local en pol\u00edtica, policiales, sociedad, deportes y servicios.","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/","logo":{"@type":"ImageObject","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2026\/01\/El-Diario.jpg","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/profile.php?id=61562291519621","https:\/\/x.com\/ElDiariodeSP","https:\/\/www.instagram.com\/eldiariosanpedro\/","https:\/\/www.youtube.com\/@eldiariosanpedro"]},{"@type":"Person","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/","name":"Fernando Gonzalez Bettendorff"},{"@type":"WebPage","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#webpage","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/","name":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","description":"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#website"},"breadcrumb":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#breadcrumblist"},"author":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author"},"creator":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/author\/fernando\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#mainImage","width":1122,"height":591},"primaryImageOfPage":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/#mainImage"},"datePublished":"2018-01-26T19:56:17-03:00","dateModified":"2018-01-26T19:56:17-03:00"},{"@type":"WebSite","@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#website","url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/","name":"El Diario de San Pedro | Noticias locales y regionales","alternateName":"El Diario de San Pedro","description":"Noticias de San Pedro y la regi\u00f3n","inLanguage":"es-ES","publisher":{"@id":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/#organization"}}]},"og:locale":"es_ES","og:site_name":"El Diario de San Pedro | Noticias locales y regionales","og:type":"article","og:title":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","og:description":"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal","og:url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/","og:image":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg","og:image:secure_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg","og:image:width":1122,"og:image:height":591,"article:published_time":"2018-01-26T22:56:17+00:00","article:modified_time":"2018-01-26T22:56:17+00:00","article:publisher":"https:\/\/facebook.com\/profile.php?id=61562291519621","twitter:card":"summary_large_image","twitter:site":"@ElDiariodeSP","twitter:title":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","twitter:description":"El Intendente Municipal lament\u00f3 la p\u00e9rdida del agente de Polic\u00eda Local Lillo y volvi\u00f3 a mostrarse disgustado con los jueces garantistas. El cuerpo de Lillo est\u00e1 siendo velado en el Sal\u00f3n Dorado de la Municipalidad de San Pedro. Una vez concluido el minuto de silencio que los vecinos brindaron al oficial Lillo, el Intendente Municipal","twitter:creator":"@ElDiariodeSP","twitter:image":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2023\/04\/cropped-favicon.png"},"aioseo_meta_data":{"post_id":"28462","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-07-12 05:11:34","updated":"2025-07-12 05:11:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/\" title=\"Locales\">Locales<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/interes-general-locales\/\" title=\"Inter\u00e9s General\">Inter\u00e9s General<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSalazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio"},{"label":"Locales","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/"},{"label":"Inter\u00e9s General","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/category\/locales\/interes-general-locales\/"},{"label":"Salazar: \u201cEs el d\u00eda m\u00e1s triste desde que asumimos esta gesti\u00f3n\u201d","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/salazar-es-el-dia-mas-triste-desde-que-asumimos-esta-gestion\/"}],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2018\/01\/El-Intendente-de-San-Pedro.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-7p4","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/28462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=28462"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/28462\/revisions"}],"predecessor-version":[{"id":28466,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/28462\/revisions\/28466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/28467"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=28462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=28462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=28462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}