{"id":150713,"date":"2026-05-08T16:15:19","date_gmt":"2026-05-08T19:15:19","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=150713"},"modified":"2026-05-08T16:15:23","modified_gmt":"2026-05-08T19:15:23","slug":"fallecio-pascual-osvaldo-puntano-a-los-80-anos","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/fallecio-pascual-osvaldo-puntano-a-los-80-anos\/","title":{"rendered":"Falleci\u00f3 Pascual Osvaldo Puntano, a los 80 a\u00f1os"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p><em>Sus restos son velados en la sala N\u00b01 de R\u00edo Tala y el servicio se extender\u00e1 hasta la ma\u00f1ana de este s\u00e1bado.<\/em><\/p>\n\n\n\n<p>Con profundo pesar fue informado el fallecimiento de <strong>Pascual Osvaldo Puntano<\/strong>, quien muri\u00f3 a los <strong>80 a\u00f1os<\/strong>. Sus restos son velados en la <strong>Sala N\u00b01 de R\u00edo Tala<\/strong>, ubicada en <strong>3 de Febrero 1475<\/strong>.<\/p>\n\n\n\n<p>El servicio de sepelio se llevar\u00e1 a cabo hasta las <strong>11:00 horas del s\u00e1bado 9 de mayo de 2026<\/strong>, seg\u00fan comunic\u00f3 <strong>Coopser Servicios Sociales<\/strong>.<\/p>\n\n\n\n<p>Familiares, amigos y allegados participan con dolor de su fallecimiento y lo despiden en las \u00faltimas horas de velatorio.<\/p>\n\n\n\n<p>#Necrologicas #Fallecimiento #PascualOsvaldoPuntano #Coopser #RioTala #ServiciosSociales<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sus restos son velados en la sala N\u00b01 de R\u00edo Tala y el servicio se extender\u00e1 hasta la ma\u00f1ana de este s\u00e1bado. Con profundo pesar fue informado el fallecimiento de Pascual Osvaldo Puntano, quien muri\u00f3 a los 80 a\u00f1os. Sus restos son velados en la Sala N\u00b01 de R\u00edo Tala, ubicada en 3 de Febrero [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":113757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8424],"tags":[10831,10141,5113,1667,8428,10830,2381,6885,9960,6088],"class_list":["post-150713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-necrologicas","tag-9-de-mayo-de-2026","tag-aviso-funebre","tag-coopser-servicios-sociales","tag-fallecimiento","tag-necrologicas","tag-pascual-osvaldo-puntano","tag-rio-tala-2","tag-sala-velatoria","tag-sepelio","tag-servicios-sociales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2023\/01\/necrologicas.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-DcR","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/150713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=150713"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/150713\/revisions"}],"predecessor-version":[{"id":150714,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/150713\/revisions\/150714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/113757"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=150713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=150713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=150713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}