{"id":150678,"date":"2026-05-08T11:24:48","date_gmt":"2026-05-08T14:24:48","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=150678"},"modified":"2026-05-08T11:24:52","modified_gmt":"2026-05-08T14:24:52","slug":"motociclista-sufrio-lesiones-leves-tras-un-choque-en-una-esquina-centrica","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/motociclista-sufrio-lesiones-leves-tras-un-choque-en-una-esquina-centrica\/","title":{"rendered":"Motociclista sufri\u00f3 lesiones leves tras un choque en una esquina c\u00e9ntrica"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p><strong>Un joven de 20 a\u00f1os fue hospitalizado luego de un accidente entre una motocicleta y un autom\u00f3vil ocurrido durante la tarde del jueves.<\/strong><\/p>\n\n\n\n<p>Un accidente de tr\u00e1nsito se registr\u00f3 durante la tarde del jueves en la intersecci\u00f3n de <strong>Bulevar Moreno y Belgrano<\/strong>, donde colisionaron una <strong>motocicleta Honda 150 cc color negra<\/strong> y un <strong>autom\u00f3vil Volkswagen blanco<\/strong>.<\/p>\n\n\n\n<p>De acuerdo a la informaci\u00f3n policial, el rodado menor era conducido por un <strong>joven de 20 a\u00f1os<\/strong>, mientras que el autom\u00f3vil estaba al mando de una <strong>mujer de 32 a\u00f1os<\/strong>. Por causas que son materia de investigaci\u00f3n, ambos veh\u00edculos impactaron en la mencionada esquina.<\/p>\n\n\n\n<p>Como consecuencia del choque, el conductor de la motocicleta fue trasladado al hospital local, donde los m\u00e9dicos constataron que presentaba <strong>lesiones de car\u00e1cter leve<\/strong>, sin complicaciones de gravedad.<\/p>\n\n\n\n<p>En el hecho interviene la <strong>Fiscal\u00eda local<\/strong>, que trabaja para establecer las circunstancias en las que se produjo el siniestro vial.<\/p>\n\n\n\n<p>#Accidente #Choque #Transito #Motociclista #LesionesLeves #Policiales #SeguridadVial #Honda150 #Fiscalia #BulevarMoreno<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven de 20 a\u00f1os fue hospitalizado luego de un accidente entre una motocicleta y un autom\u00f3vil ocurrido durante la tarde del jueves. Un accidente de tr\u00e1nsito se registr\u00f3 durante la tarde del jueves en la intersecci\u00f3n de Bulevar Moreno y Belgrano, donde colisionaron una motocicleta Honda 150 cc color negra y un autom\u00f3vil Volkswagen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":150679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-150678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2026\/05\/choque-1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-Dci","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/150678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=150678"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/150678\/revisions"}],"predecessor-version":[{"id":150680,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/150678\/revisions\/150680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/150679"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=150678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=150678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=150678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}