{"id":1351,"date":"2015-12-09T11:14:47","date_gmt":"2015-12-09T14:14:47","guid":{"rendered":"http:\/\/www.eldiariodesanpedro.com.ar\/?p=1351"},"modified":"2015-12-09T11:14:47","modified_gmt":"2015-12-09T14:14:47","slug":"1351-2","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/1351-2\/","title":{"rendered":"Francisco inst\u00f3 a la Iglesia a abrirse al mundo al inaugurar el jubileo"},"content":{"rendered":"<p><!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. --><br \/>\n(AFP-NA) &#8211; El papa Francisco inst\u00f3 este martes a la Iglesia \u00aba abrirse al mundo\u00bb durante la misa de inauguraci\u00f3n en la plaza de San Pedro del Jubileo \u00abde la misericordia y el perd\u00f3n\u00bb, momento culminante de su pontificado.<br \/>\n   Al t\u00e9rmino de la misa, el papa abri\u00f3 en forma solemne y hablando en italiano -y no en lat\u00edn como es la tradici\u00f3n,- la puerta santa de la bas\u00edlica, que permanece sellada a cal y canto todo el a\u00f1o.<br \/>\n   Al ritual asisti\u00f3 el papa em\u00e9rito Benedicto XVI, de 88 a\u00f1os.<br \/>\nAs\u00ed, por primera vez en la historia, dos papas inauguraron un jubileo.<br \/>\n   La ceremonia, a la que asistieron unas 70.000 personas, estuvo marcada por las imponentes medidas de seguridad alrededor del Vaticano y en el casco hist\u00f3rico de Roma, tomadas tras los atentados de Par\u00eds que el 13 noviembre costaron la vida a 130 personas.<br \/>\n   El papa, de 78 a\u00f1os, con el rostro serio y algo cansado, celebr\u00f3 primero la misa desde un altar instalado frente a la explanada ante cientos de cardenales, obispos y sacerdotes, adem\u00e1s de fieles, muchos de ellos provenientes de toda Italia.<br \/>\n   \u00abHoy (por ayer) cruzando la Puerta Santa queremos tambi\u00e9n recordar otra puerta que, hace cincuenta a\u00f1os, los padres del Concilio Vaticano II abrieron hacia el mundo (&#8230;). Fue un verdadero encuentro entre la Iglesia y los hombres de nuestro tiempo\u00bb, dijo.<br \/>\n   Para el papa fue \u00abun impulso misionero\u00bb para que la Iglesia \u00abvuelva a tomar el camino para ir al encuentro de cada hombre all\u00ed donde vive: en su ciudad, en su casa, en el trabajo\u00bb, dijo.<br \/>\n   Francisco invit\u00f3 a la Iglesia a recuperar el \u00abesp\u00edritu del samaritano\u00bb, para salir a proclamar la alegr\u00eda del amor al mundo, el perd\u00f3n y la reconciliaci\u00f3n.<br \/>\n   Una larga procesi\u00f3n de cardenales, obispos, sacerdotes, religiosos y laicos atravesaron luego la puerta y desfilaron hacia la tumba de Pedro, el fundador de la Iglesia.<br \/>\n   \u00abDeseaba estar aqu\u00ed porque se trata de un mensaje de paz que el jubileo quiere transmitir en este momento de inestabilidad en todo el mundo\u00bb, cont\u00f3 Mar\u00eda, una se\u00f1ora siciliana entrevistada por la televisi\u00f3n p\u00fablica Rai News.<br \/>\n   \u00abNo tengo miedo, venci\u00f3 la emoci\u00f3n\u00bb, reconoci\u00f3 por su parte una joven estudiante de la isla de Cerde\u00f1a que se dispon\u00eda a hacer fila para cruzar la puerta santa.<br \/>\n   El papa record\u00f3 que a quienes cruzar\u00e1n la Puerta Santa durante el a\u00f1o del jubileo, que se concluye el 20 de noviembre del 2016, se les conceder\u00e1 el perd\u00f3n de los pecados y la indulgencia plena.<br \/>\n   Poco despu\u00e9s, pronunci\u00f3 el \u00e1ngelus pronunciado desde la ventana del palacio apost\u00f3lico y en la tarde rindi\u00f3 homenaje en la romana Plaza de Espa\u00f1a a la estatua de Virgen de la Inmaculada Concepci\u00f3n.<br \/>\n   \u00abVengo en nombre de aquellos que vienen de tierras lejanas en busca de paz y trabajo\u00bb, dijo el papa argentino, al saludar y abrazar uno por uno y en medio de aplausos a un grupo de ancianos y enfermos.<\/p>\n<p> A\u00f1o Santo \u00abextraordinario\u00bb <\/p>\n<p>   El primer A\u00f1o Santo de Francisco se celebra 15 a\u00f1os despu\u00e9s del jubileo del a\u00f1o 2000 convocado por Juan Pablo II y tiene un car\u00e1cter \u00abextraordinario\u00bb a diferencia del \u00abordinario\u00bb, que se organiza cada 25 a\u00f1os.<br \/>\n   Al menos 21 actos han sido programados con j\u00f3venes, enfermos y presos, as\u00ed como visitas privadas de solidaridad con pobres y olvidados.<br \/>\n   Francisco envi\u00f3 un mensaje particular a las mujeres con su anuncio en septiembre de que autorizaba a los sacerdotes a perdonar a las mujeres que han abortado.<br \/>\n   Roma ha sido blindada por la llegada de miles de peregrinos con casi 3.000 agentes y militares desplegados en puntos claves de la ciudad y ha instalado m\u00e1s detectores de metales y videoc\u00e1maras para vigilar la explanada de San Pedro adem\u00e1s de haber cerrado el espacio a\u00e9reo.<br \/>\n   Cinco d\u00edas despu\u00e9s, el 13 de diciembre, por primera vez en la historia, las puertas santas de todas las catedrales del mundo ser\u00e1n abiertas: Por primera vez en siete siglos no ser\u00e1 necesario viajar a Roma para obtener la indulgencia plenaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(AFP-NA) &#8211; El papa Francisco inst\u00f3 este martes a la Iglesia \u00aba abrirse al mundo\u00bb durante la misa de inauguraci\u00f3n en la plaza de San Pedro del Jubileo \u00abde la misericordia y el perd\u00f3n\u00bb, momento culminante de su pontificado. Al t\u00e9rmino de la misa, el papa abri\u00f3 en forma solemne y hablando en italiano -y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1353,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2015\/12\/Papa-Francisco.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-lN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/1351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=1351"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/1351\/revisions"}],"predecessor-version":[{"id":1354,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/1351\/revisions\/1354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/1353"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=1351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=1351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=1351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}