{"id":133925,"date":"2024-10-18T15:46:14","date_gmt":"2024-10-18T18:46:14","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=133925"},"modified":"2024-10-18T15:46:18","modified_gmt":"2024-10-18T18:46:18","slug":"cursos-del-programa-cuidarnos-en-red-prevencion-de-apuestas-en-adolescentes","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/cursos-del-programa-cuidarnos-en-red-prevencion-de-apuestas-en-adolescentes\/","title":{"rendered":"Cursos del programa Cuidarnos en Red: Prevenci\u00f3n de apuestas en adolescentes"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>La Municipalidad de San Pedro, a trav\u00e9s de la Secretar\u00eda de Salud y la Direcci\u00f3n de Salud Mental, informa sobre las nuevas ediciones 2024 de los cursos ofrecidos por el Programa interministerial Cuidarnos en Red de la provincia de Buenos Aires, dirigidos a trabajadores y trabajadoras estatales provinciales y municipales.<\/p>\n\n\n\n<p>En esta oportunidad, se llevar\u00e1 a cabo el curso \u201cApuestas online en la adolescencia: Herramientas para la prevenci\u00f3n, protecci\u00f3n y acceso a la justicia\u201d .<\/p>\n\n\n\n<p>Este curso tiene como objetivo mejorar la gesti\u00f3n p\u00fablica ante conflictos en entornos digitales, fortaleciendo las respuestas estatales y facilitando el acceso a la justicia, el acompa\u00f1amiento y la protecci\u00f3n de las personas afectadas por estas problem\u00e1ticas.<\/p>\n\n\n\n<p>Detalles del curso:<\/p>\n\n\n\n<p>Inicio: 30 de octubre<br>Modalidad: A distancia a trav\u00e9s de la plataforma digital del Instituto Provincial de la Administraci\u00f3n P\u00fablica (IPAP).<br>Duraci\u00f3n: Un mes<br>Acreditaci\u00f3n: 10 horas de capacitaci\u00f3n<\/p>\n\n\n\n<p>El curso est\u00e1 destinado a trabajadores y trabajadores municipales y provinciales que pertenezcan a la Red de atenci\u00f3n en Salud Mental, as\u00ed como a \u00e1reas de g\u00e9nero, juventudes, ni\u00f1ez, salud y seguridad municipales. Se enfoca en proporcionar herramientas y conocimientos sobre el fen\u00f3meno de las apuestas online, con el objetivo de mejorar el abordaje del consumo problem\u00e1tico en adolescentes y j\u00f3venes. Adem\u00e1s, promueve el desarrollo de estrategias de prevenci\u00f3n comunitaria y ofrece informaci\u00f3n sobre los mecanismos de denuncia de sitios ilegales.<\/p>\n\n\n\n<p>Inscripci\u00f3n abierta hasta el 20 de octubre.<\/p>\n\n\n\n<p>Para realizar la inscripci\u00f3n y obtener m\u00e1s informaci\u00f3n pueden ingresar al siguiente enlace: <a href=\"https:\/\/bit.ly\/3YskZA0\">https:\/\/bit.ly\/3YskZA0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de San Pedro, a trav\u00e9s de la Secretar\u00eda de Salud y la Direcci\u00f3n de Salud Mental, informa sobre las nuevas ediciones 2024 de los cursos ofrecidos por el Programa interministerial Cuidarnos en Red de la provincia de Buenos Aires, dirigidos a trabajadores y trabajadoras estatales provinciales y municipales. En esta oportunidad, se llevar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":133926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[101,2],"tags":[],"class_list":["post-133925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-general-locales","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2024\/10\/medida-18.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-yQ5","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/133925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=133925"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/133925\/revisions"}],"predecessor-version":[{"id":133927,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/133925\/revisions\/133927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/133926"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=133925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=133925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=133925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}