{"id":133846,"date":"2024-10-16T14:10:13","date_gmt":"2024-10-16T17:10:13","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=133846"},"modified":"2024-10-16T14:10:17","modified_gmt":"2024-10-16T17:10:17","slug":"ultima-jornada-de-la-capacitacion-en-tecnologias-para-adultos-mayores","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/ultima-jornada-de-la-capacitacion-en-tecnologias-para-adultos-mayores\/","title":{"rendered":"\u00daltima Jornada de la Capacitaci\u00f3n en Tecnolog\u00edas para Adultos Mayores"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>Este martes, la Direcci\u00f3n de Adultos Mayores de la Municipalidad de San Pedro llev\u00f3 a cabo la \u00faltima de las cuatro clases establecidas del programa \u00abUso de Tecnolog\u00edas para Adultos Mayores\u00bb en conjunto con la Direcci\u00f3n de Promoci\u00f3n de Derechos de las Personas Mayores del Ministerio de Desarrollo de la Comunidad de la Provincia de Buenos Aires.<\/p>\n\n\n\n<p>Estas charlas, se concretaron con el objetivo de facilitar el acceso a las herramientas tecnol\u00f3gicas. Participaron del encuentro los adultos mayores de las localidades de Santa Luc\u00eda y R\u00edo Tala.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes, la Direcci\u00f3n de Adultos Mayores de la Municipalidad de San Pedro llev\u00f3 a cabo la \u00faltima de las cuatro clases establecidas del programa \u00abUso de Tecnolog\u00edas para Adultos Mayores\u00bb en conjunto con la Direcci\u00f3n de Promoci\u00f3n de Derechos de las Personas Mayores del Ministerio de Desarrollo de la Comunidad de la Provincia de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":133847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[101,2],"tags":[],"class_list":["post-133846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interes-general-locales","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2024\/10\/Imagen-de-WhatsApp-2024-10-16-a-las-09.38.41_a0217989.jpg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-yOO","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/133846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=133846"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/133846\/revisions"}],"predecessor-version":[{"id":133848,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/133846\/revisions\/133848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/133847"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=133846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=133846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=133846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}