{"id":100643,"date":"2021-10-25T10:31:53","date_gmt":"2021-10-25T13:31:53","guid":{"rendered":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/?p=100643"},"modified":"2021-10-25T10:31:56","modified_gmt":"2021-10-25T13:31:56","slug":"informe-de-la-jefatura-distrital-de-educacion-sobre-la-situacion-escolar-la-implementacion-del-atr-y-la-planificacion-para-los-proximos-meses","status":"publish","type":"post","link":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/informe-de-la-jefatura-distrital-de-educacion-sobre-la-situacion-escolar-la-implementacion-del-atr-y-la-planificacion-para-los-proximos-meses\/","title":{"rendered":"Informe de la Jefatura Distrital de Educaci\u00f3n sobre la situaci\u00f3n escolar, la implementaci\u00f3n del +ATR y la planificaci\u00f3n para los pr\u00f3ximos meses"},"content":{"rendered":"<!-- VideographyWP Plugin Message: Automatic video embedding prevented by plugin options. -->\n\n<p>La Jefatura Distrital de Educaci\u00f3n puso a disposici\u00f3n del gobierno municipal un informe sobre la situaci\u00f3n actual del Partido de San Pedro, continuando con las acciones coordinadas planteadas entre el Intendente Municipal Cecilio Salazar y la titular de la Jefatura Marcela Lucchesi.<\/p>\n\n\n\n<p>Sigue adelante el plan de Presencialidad Cuidada encuadrado en el protocolo de regreso a clases presenciales cuidadas, en los niveles inicial, primario y secundaria, y la implementaci\u00f3n del programa del Fortalecimiento de la Ense\u00f1anza +ATR.<\/p>\n\n\n\n<p>Desde el 1\u00b0 de septiembre la mayor\u00eda de los alumnos volvieron a las escuelas y s\u00f3lo en algunos cursos de matr\u00edcula de mayor volumen se sostienen clases con asistencia programada.<\/p>\n\n\n\n<p>Desde el gobierno de la Provincia de Buenos Aires se enviaron 210 equipos de medici\u00f3n de di\u00f3xido de carbono para controlar la necesidad de ventilaci\u00f3n en los ambientes escolares que fueron distribuidos en las escuelas del Partido y se mantienen operativos a la fecha, adem\u00e1s se han realizado testeos r\u00e1pidos por casos de Covid-19 en las instituciones educativas articulando con la Secretar\u00eda de Salud.<\/p>\n\n\n\n<p>Para intensificar los tiempos de ense\u00f1anza a contra-turno los s\u00e1bados se conforman dispositivos de clases para los chicos y chicas que as\u00ed lo requieran, convocando especialmente a aquellos j\u00f3venes que forman parte de un registro nominal con informes individuales y que resulta conveniente acompa\u00f1ar con esta modalidad.<\/p>\n\n\n\n<p>Este programa denominado +ATR Fortalecimiento de la Ense\u00f1anza, atiende a esta cuesti\u00f3n, promoviendo m\u00e1s tiempo y m\u00e1s aprendizajes en la escuela.<\/p>\n\n\n\n<p>Del total de la matr\u00edcula de primaria y secundaria, el 81% tiene una trayectoria educativa afianzada, es decir que se le ha ense\u00f1ado y han aprendido los contenidos priorizados para el a\u00f1o, mientras que el 19% restante se divide en diferentes categor\u00edas.<\/p>\n\n\n\n<p>El 15,8% se encuentra con la necesidad de reponer algunos saberes en algunas \u00e1reas curriculares. Entre ellos, estudiantes de secundario que habitualmente hubiesen promocionado con dos previas y otros en situaciones m\u00e1s cr\u00edticas. Finalmente hay un 3.1 % con una mayor proporci\u00f3n de secundaria que de primaria con desvinculaci\u00f3n pedag\u00f3gica.<\/p>\n\n\n\n<p>Los ATR s\u00f3lo son obligatorios para los alumnos que se encuentran en las condiciones educativas antes mencionadas, y la convocatoria a participar se ha realizado desde cada establecimiento en comunicaci\u00f3n con las familias. Se han planificado actividades hasta diciembre, con un receso en enero, pero con una propuesta optativa de +ATR Verano para ese mes, previo al reinicio formal desde febrero.<\/p>\n\n\n\n<p>Antes del inicio del ciclo lectivo 2022, en marzo, se evaluar\u00e1 la situaci\u00f3n de acreditaci\u00f3n o promoci\u00f3n para el a\u00f1o siguiente de cada uno de los chicos y chicas incluidos en el programa.<\/p>\n\n\n\n<p>En San Pedro, hasta el momento hay 170 cargos docentes para sostener esta propuesta de 7 meses de duraci\u00f3n. Se promueven los cargos para su cobertura bajo los sistemas habituales, incluyendo nombramientos de personal auxiliar para los d\u00edas s\u00e1bados.<\/p>\n\n\n\n<p>Finalmente se destaca que, desde la Gesti\u00f3n Educativa Provincial se han creado Equipos de Orientaci\u00f3n Escolar en escuelas que a\u00fan no contaban con ellos. Los profesionales reciben capacitaciones constantes para responder con una mayor eficacia a la hora de planificar y atender las necesidades de los alumnos y alumnas en materia de ense\u00f1anza, desde la modalidad de Psicolog\u00eda Comunitaria y Pedagog\u00eda Social.<\/p>\n\n\n\n<p>En San Pedro fueron incorporados estos equipos a cuatro escuelas primarias y a 6 escuelas secundarias, completando adem\u00e1s con la creaci\u00f3n de tres cargos los equipos de tres escuelas primarias.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-attachment-id=\"100644\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/informe-de-la-jefatura-distrital-de-educacion-sobre-la-situacion-escolar-la-implementacion-del-atr-y-la-planificacion-para-los-proximos-meses\/whatsapp-image-2021-10-25-at-10-09-11\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11.jpeg\" data-orig-size=\"1024,768\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-10-25 at 10.09.11\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11.jpeg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11.jpeg\" alt=\"\" class=\"wp-image-100644 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11.jpeg 1024w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11-300x225.jpeg 300w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11-768x576.jpeg 768w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.11-500x375.jpeg 500w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"931\" height=\"1024\" data-attachment-id=\"100645\" data-permalink=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/informe-de-la-jefatura-distrital-de-educacion-sobre-la-situacion-escolar-la-implementacion-del-atr-y-la-planificacion-para-los-proximos-meses\/whatsapp-image-2021-10-25-at-10-09-12-1\/\" data-orig-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12-1.jpeg\" data-orig-size=\"931,1024\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-10-25 at 10.09.12 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12-1.jpeg\" data-src=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12-1.jpeg\" alt=\"\" class=\"wp-image-100645 lazyload\" data-srcset=\"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12-1.jpeg 931w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12-1-273x300.jpeg 273w, https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12-1-768x845.jpeg 768w\" data-sizes=\"(max-width: 931px) 100vw, 931px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 931px; --smush-placeholder-aspect-ratio: 931\/1024;\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Jefatura Distrital de Educaci\u00f3n puso a disposici\u00f3n del gobierno municipal un informe sobre la situaci\u00f3n actual del Partido de San Pedro, continuando con las acciones coordinadas planteadas entre el Intendente Municipal Cecilio Salazar y la titular de la Jefatura Marcela Lucchesi. Sigue adelante el plan de Presencialidad Cuidada encuadrado en el protocolo de regreso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":100646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[50,101,2],"tags":[],"class_list":["post-100643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-interes-general-locales","category-locales"],"aioseo_notices":[],"gutentor_comment":0,"jetpack_featured_media_url":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-25-at-10.09.12.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p6RhLt-qbh","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/100643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=100643"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/100643\/revisions"}],"predecessor-version":[{"id":100647,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/100643\/revisions\/100647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media\/100646"}],"wp:attachment":[{"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=100643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=100643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodesanpedro.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=100643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}